{"id":4661,"date":"2019-06-23T18:38:29","date_gmt":"2019-06-23T16:38:29","guid":{"rendered":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg"},"modified":"2019-11-17T20:13:29","modified_gmt":"2019-11-17T18:13:29","slug":"estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2","status":"inherit","type":"attachment","link":"https:\/\/www.evento.love\/blog\/5-consejos-para-el-candy-bar-de-tu-boda\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2\/","title":{"rendered":"estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":{"content-type":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2 - El Blog de evento.love<\/title>\n<meta name=\"description\" content=\"Si has estado en uno de nuestros eventos en Madrid ya nos conoces, sino a\u00fan est\u00e1s a tiempo de organizar tu fiesta ideal. \u00a1Compru\u00e9balo!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2 - El Blog de evento.love\" \/>\n<meta property=\"og:description\" content=\"Si has estado en uno de nuestros eventos en Madrid ya nos conoces, sino a\u00fan est\u00e1s a tiempo de organizar tu fiesta ideal. \u00a1Compru\u00e9balo!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg\" \/>\n<meta property=\"og:site_name\" content=\"El Blog de evento.love\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Evento.love\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-17T18:13:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"567\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Evento_love\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2 - El Blog de evento.love","description":"Si has estado en uno de nuestros eventos en Madrid ya nos conoces, sino a\u00fan est\u00e1s a tiempo de organizar tu fiesta ideal. \u00a1Compru\u00e9balo!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2 - El Blog de evento.love","og_description":"Si has estado en uno de nuestros eventos en Madrid ya nos conoces, sino a\u00fan est\u00e1s a tiempo de organizar tu fiesta ideal. \u00a1Compru\u00e9balo!","og_url":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg","og_site_name":"El Blog de evento.love","article_publisher":"https:\/\/www.facebook.com\/Evento.love\/","article_modified_time":"2019-11-17T18:13:29+00:00","og_image":[{"width":850,"height":567,"url":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Evento_love","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg","url":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg","name":"estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2 - El Blog de evento.love","isPartOf":{"@id":"https:\/\/www.evento.love\/blog\/#website"},"datePublished":"2019-06-23T16:38:29+00:00","dateModified":"2019-11-17T18:13:29+00:00","description":"Si has estado en uno de nuestros eventos en Madrid ya nos conoces, sino a\u00fan est\u00e1s a tiempo de organizar tu fiesta ideal. \u00a1Compru\u00e9balo!","breadcrumb":{"@id":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Evento.love","item":"https:\/\/www.evento.love\/blog\/"},{"@type":"ListItem","position":2,"name":"Bodas","item":"https:\/\/www.evento.love\/blog\/category\/bodas\/"},{"@type":"ListItem","position":3,"name":"5 consejos para el candy bar de tu boda","item":"https:\/\/www.evento.love\/blog\/5-consejos-para-el-candy-bar-de-tu-boda\/"},{"@type":"ListItem","position":4,"name":"estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2"}]},{"@type":"WebSite","@id":"https:\/\/www.evento.love\/blog\/#website","url":"https:\/\/www.evento.love\/blog\/","name":"El Blog de evento.love","description":"T\u00fa lo mereces. Disfruta de tu momento","publisher":{"@id":"https:\/\/www.evento.love\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.evento.love\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.evento.love\/blog\/#organization","name":"evento.love","url":"https:\/\/www.evento.love\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.evento.love\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2016\/07\/logo-evento-love.png","contentUrl":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2016\/07\/logo-evento-love.png","width":197,"height":59,"caption":"evento.love"},"image":{"@id":"https:\/\/www.evento.love\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Evento.love\/","https:\/\/twitter.com\/Evento_love","https:\/\/www.instagram.com\/evento.love\/","https:\/\/es.pinterest.com\/evento_love\/","https:\/\/www.youtube.com\/channel\/UCcVbo6ymzx-7FlDJja8aQnw"]}]}},"smush":{"stats":{"percent":4.327762115720231,"bytes":5158,"size_before":119184,"size_after":114026,"time":0.09,"api_version":"1.0","lossy":false,"keep_exif":0},"sizes":{"thumbnail":{"percent":5.99,"bytes":407,"size_before":6791,"size_after":6384,"time":0.01},"medium":{"percent":5.51,"bytes":818,"size_before":14851,"size_after":14033,"time":0.01},"medium_large":{"percent":4.05,"bytes":2718,"size_before":67043,"size_after":64325,"time":0.02},"post-thumbnail":{"percent":5.04,"bytes":1215,"size_before":24115,"size_after":22900,"time":0.04},"wp_rp_thumbnail":{"percent":0,"bytes":0,"size_before":6384,"size_after":6384,"time":0.01}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg'><img width=\"300\" height=\"200\" src=\"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"estructura de globos rosa y dorado\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-300x200.jpg 300w, https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-768x512.jpg 768w, https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-405x270.jpg 405w, https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg 850w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->"},"caption":{"rendered":"<p><!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n"},"alt_text":"estructura de globos rosa y dorado","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":850,"height":567,"file":"2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg","sizes":{"thumbnail":{"file":"estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-150x150.jpg"},"medium":{"file":"estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-300x200.jpg"},"medium_large":{"file":"estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-768x512.jpg"},"post-thumbnail":{"file":"estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-405x270.jpg","width":405,"height":270,"mime_type":"image\/jpeg","source_url":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-405x270.jpg"},"wp_rp_thumbnail":{"file":"estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2-150x150.jpg"},"full":{"file":"estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg","width":850,"height":567,"mime_type":"image\/jpeg","source_url":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"Sergio Glotzer","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0"}},"post":5608,"source_url":"https:\/\/www.evento.love\/blog\/wp-content\/uploads\/2019\/06\/estructura-globos-rosa-dorado-mesa-dulce-evento-love-bautizo-2.jpg","_links":{"self":[{"href":"https:\/\/www.evento.love\/blog\/wp-json\/wp\/v2\/media\/4661"}],"collection":[{"href":"https:\/\/www.evento.love\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.evento.love\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.evento.love\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.evento.love\/blog\/wp-json\/wp\/v2\/comments?post=4661"}]}}